{"id":1353,"date":"2021-05-04T08:23:40","date_gmt":"2021-05-04T01:23:40","guid":{"rendered":"https:\/\/wellnessexpo.com.vn\/home\/"},"modified":"2025-07-11T09:56:39","modified_gmt":"2025-07-11T02:56:39","slug":"home","status":"publish","type":"page","link":"https:\/\/wellnessexpo.com.vn\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t<section class=\"section\" id=\"section_770704601\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-1211007001\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 4000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_285182283\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1000\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/07\/Banner-WN25-2560x1000px-02-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/07\/Banner-WN25-2560x1000px-02-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/07\/Banner-WN25-2560x1000px-02-300x117.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/07\/Banner-WN25-2560x1000px-02-1024x400.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/07\/Banner-WN25-2560x1000px-02-768x300.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/07\/Banner-WN25-2560x1000px-02-1536x600.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/07\/Banner-WN25-2560x1000px-02-2048x800.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_285182283 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1482209703\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1000\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/z6711281208176_eee7a45898819a3f226c1cced58e7ff2.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/z6711281208176_eee7a45898819a3f226c1cced58e7ff2.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/z6711281208176_eee7a45898819a3f226c1cced58e7ff2-300x117.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/z6711281208176_eee7a45898819a3f226c1cced58e7ff2-1024x400.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/z6711281208176_eee7a45898819a3f226c1cced58e7ff2-768x300.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/z6711281208176_eee7a45898819a3f226c1cced58e7ff2-1536x600.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/z6711281208176_eee7a45898819a3f226c1cced58e7ff2-2048x800.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1482209703 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_770704601 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"ocean\">\n<div class=\"wave\"><\/div>\n<div class=\"wave\"><\/div>\n<\/div>\n\t<section class=\"section\" id=\"section_1768330448\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\"  id=\"row-2128654159\">\n\n\t<div id=\"col-917018094\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container dich-vu-section\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Exhibition overview<\/span><b><\/b><\/h2><\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-917018094 > .col-inner {\n  padding: 50px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1190707150\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover bdr-inc x md-x lg-x y md-y lg-y\" id=\"image_698483881\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-zoom dark\" >\n\t\t\t<img decoding=\"async\" width=\"432\" height=\"315\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/Logo-wellness-ai.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/Logo-wellness-ai.png 432w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/Logo-wellness-ai-300x219.png 300w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_698483881 {\n  width: 79%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-660026310\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<blockquote><p><strong>The International Wellness Food, Healthcare Industry &amp; Lifestyle Expo (Wellness Expo)<\/strong>\u00a0is not simply a trade exhibition focusing on displaying products, technology, healthcare services and lifestyle, but above all Wellness Expo always wants to accompany the community on its journey. Build a\u00a0<strong>\u201cHealthy Living Journey\u201d<\/strong>. Every year, Wellness Expo will bring a different theme, focusing on exploiting and building a \u201cHealthy Living Journey\u201d in different aspects to contribute to creating a comprehensive and enhanced healthy life. health and quality of life of Vietnamese people.<\/p>\n<p>With a health foundation that has been nurtured from safe, benign and quality natural products, Wellness Expo will continue to explore with you the \u201cHealthy Living Journey\u201d with new topics and advanced stages. levels over the years to lead a comprehensive healthy lifestyle.<\/p><\/blockquote>\n<a href=\"\/gioi-thieu\" target=\"_self\" class=\"button primary is-outline bttt-inc\"  style=\"border-radius:10px;\">\n    <span>Find out more<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row dkgh-inc\"  id=\"row-2056451787\">\n\n\t<div id=\"col-159631444\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"uppercase\" style=\"text-align: center;\"><a href=\"https:\/\/wellnessexpo.com.vn\/en\/booth-registration\/\">Register<br \/>\nstalls<\/a><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1084253202\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"uppercase\" style=\"text-align: center;\"><a href=\"https:\/\/wellnessexpo.com.vn\/en\/visitor-registration\/\">Register<br \/>\nsightseeing<\/a><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1205187715\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"uppercase\" style=\"text-align: center;\"><a href=\"https:\/\/wellnessexpo.com.vn\/en\/business-matching-registration\/\">Register<br \/>\ntrade connection<\/a><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1000097879\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"uppercase\" style=\"text-align: center;\"><a href=\"https:\/\/wellnessexpo.com.vn\/en\/seminar-registration\/\">Register<br \/>\nseminar<\/a><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1768330448 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section dich-vu-section\" id=\"section_450576837\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1255756845\">\n\n\t<div id=\"col-1910535949\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container dich-vu-section\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Exhibition field<\/span><b><\/b><\/h2><\/div>\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-line-bottom nav-uppercase nav-size-large nav-right\"><li class=\"tab active has-icon\"><a href=\"#tab_all\"><span>All<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div class=\"panel active entry-content\" id=\"tab_all\">\n<div class=\"row\"  id=\"row-948807258\">\n\n\t<div id=\"col-1549613843\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Nutritional food &amp; drink<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/1-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/1-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/1-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/1-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/1-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/1-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/1-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1908787882\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Health &amp; wellness<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"626\" height=\"417\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/2.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/2.jpg 626w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/2-300x200.jpg 300w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-484435613\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Beauty Products &amp; Services<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1709\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/3-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/3-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/3-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/3-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/3-768x513.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/3-1536x1025.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/3-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-527343830\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Technology and smart devices<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/4-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/4-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/4-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/4-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/4-768x513.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/4-1536x1025.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/4-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-731587811\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Sports<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"740\" height=\"492\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/5.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/5.jpg 740w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/5-300x199.jpg 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1412044274\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Ornate<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/6.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/6.jpg 1920w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/6-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/6-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/6-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/6-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1731745880\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Tourism<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/7-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/7-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/7-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/7-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/7-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/7-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/7-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-82156577\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Other<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"\/nha-trung-bay\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:250px;\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/8-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/8-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/8-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/8-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/8-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/8-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/8-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<\/div><\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_450576837 {\n  padding-top: 43px;\n  padding-bottom: 43px;\n  background-color: rgb(248, 249, 250);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section khach-hang-section\" id=\"section_1391733125\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-835104824\">\n\n\t<div id=\"col-1230621938\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Featured news<\/span><b><\/b><a href=\"\/tin-tuc\" target=\"\">Xem t\u1ea5t c\u1ea3<i class=\"icon-angle-right\" ><\/i><\/a><\/h2><\/div>\n\n  \n    <div class=\"row post-noi-bat large-columns-1 medium-columns-1 small-columns-1 row-small\">\n  <\/div>\n\n  \n    <div class=\"row list-post2 large-columns-2 medium-columns-1 small-columns-1 slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": true, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  \t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wellnessexpo.com.vn\/en\/press-release-officially-opened-of-the-international-wellness-food-healthcare-industry-lifestyle-expo-2024-in-vietnam-wellness-expo-2024\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-vertical box-text-top box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:35%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:69%;\">\n  \t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1000\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-300x117.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-1024x400.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-768x300.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-1536x600.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-2048x800.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t                                                   \t\t\t\t\t\t  \t\t\t\t\t<\/div><!-- .box-image -->\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">PRESS RELEASE OFFICIALLY OPENED OF THE INTERNATIONAL WELLNESS FOOD HEALTHCARE INDUSTRY &#038; LIFESTYLE EXPO 2024 IN VIETNAM (WELLNESS EXPO 2024)<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div><!-- .box-text-inner -->\n\t\t\t\t\t<\/div><!-- .box-text -->\n\t\t\t\t\t\t\t\t\t<\/div><!-- .box -->\n\t\t\t\t<\/a><!-- .link -->\n\t\t\t<\/div><!-- .col-inner -->\n\t\t<\/div><!-- .col -->\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wellnessexpo.com.vn\/en\/international-exhibition-on-healthcare-products-and-lifestyle-2024-wellness-expo-2024-coming-back-with-the-theme-healthy-life-with-nature\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-vertical box-text-top box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:35%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:69%;\">\n  \t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1000\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-300x117.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-1024x400.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-768x300.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-1536x600.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-2048x800.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t                                                   \t\t\t\t\t\t  \t\t\t\t\t<\/div><!-- .box-image -->\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">INTERNATIONAL EXHIBITION ON HEALTHCARE PRODUCTS AND LIFESTYLE 2024 (WELLNESS EXPO 2024) COMING BACK WITH THE THEME \u201cHEALTHY LIFE WITH NATURE\u201d<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div><!-- .box-text-inner -->\n\t\t\t\t\t<\/div><!-- .box-text -->\n\t\t\t\t\t\t\t\t\t<\/div><!-- .box -->\n\t\t\t\t<\/a><!-- .link -->\n\t\t\t<\/div><!-- .col-inner -->\n\t\t<\/div><!-- .col -->\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wellnessexpo.com.vn\/en\/tong-hop-tin-bai-ve-trien-lam-wellness-expo-2024-dot-1\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-vertical box-text-top box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:35%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:69%;\">\n  \t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1000\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-300x117.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-1024x400.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-768x300.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-1536x600.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/z6074672292926_c362d3600d8e8cfc1f169f9079a1627c-2048x800.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t                                                   \t\t\t\t\t\t  \t\t\t\t\t<\/div><!-- .box-image -->\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">T\u1ed4NG H\u1ee2P TIN B\u00c0I V\u1ec0 TRI\u1ec2N L\u00c3M WELLNESS EXPO 2024 &#8211; \u0110\u1ee2T 1<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div><!-- .box-text-inner -->\n\t\t\t\t\t<\/div><!-- .box-text -->\n\t\t\t\t\t\t\t\t\t<\/div><!-- .box -->\n\t\t\t\t<\/a><!-- .link -->\n\t\t\t<\/div><!-- .col-inner -->\n\t\t<\/div><!-- .col -->\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1391733125 {\n  padding-top: 51px;\n  padding-bottom: 51px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section video-section\" id=\"section_285468143\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1380669016\">\n\n\t<div id=\"col-348273660\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-1202474612\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1202474612 {\n  padding-top: 9px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 class=\"uppercase\"><span style=\"font-size: 150%; color: #3c3469;\">Video Library<\/span><\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-1637309361\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1637309361 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-179598393\">\n\n\t<div id=\"col-1501459700\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"T\u1ed5ng k\u1ebft Tri\u1ec3n l\u00e3m Wellness Expo 2024\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/uZhnJLIY-kg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-399780963\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-652203842\">\n\n\t<div id=\"col-958002182\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/gallery-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/gallery-300x300.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/gallery-150x150.png 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/gallery.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-1912960436\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1912960436 {\n  padding-top: 9px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 class=\"uppercase\"><span style=\"font-size: 150%; color: #3c3469;\">Photo library<\/span><\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-805471542\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-805471542 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1899288871\">\n\n\t<div id=\"col-2105012935\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n          <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05439-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05487-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05511-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05705-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05753-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05745-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05723-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05729-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05744-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05712-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05722-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05752-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05840-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05772-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05910-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05902-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05501-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05507-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05567-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05610-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05980-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05602-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05527-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05592-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06095-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05558-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU05546-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-scaled.jpg\" title=\"Wellness Expo 2024\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-3-hover image-cover\" style=\"padding-top:250px;\">\n                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"4688,4690,4696,4714,4730,4726,4720,4722,4724,4716,4718,4728,4734,4732,4738,4736,4692,4694,4706,4712,4682,4710,4698,4708,4684,4702,4700,4686\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" columns__sm=\"2\" depth=\"2\" depth_hover=\"3\" image_height=\"250px\" image_size=\"original\" text_align=\"center\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-scaled.jpg 2560w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-1024x683.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-768x512.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-1536x1024.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2025\/06\/DZU06114-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>Wellness Expo 2024<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n         <\/div>\n\n  \n    <div class=\"row hidden large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n          <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-2.jpg\" title=\"aaaaaaaaaaaa\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"800\" height=\"553\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-2.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-2.jpg 800w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-2-300x207.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-2-768x531.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>aaaaaaaaaaaa<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hinh2.jpg\" title=\"sssssssssssssss\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"640\" height=\"429\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hinh2.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hinh2.jpg 640w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hinh2-300x201.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>sssssssssssssss<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/images1407654_dao_1.jpg\" title=\"ddddddd\u0111\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/images1407654_dao_1.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/images1407654_dao_1.jpg 1920w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/images1407654_dao_1-300x169.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/images1407654_dao_1-1024x576.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/images1407654_dao_1-768x432.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/images1407654_dao_1-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>ddddddd\u0111<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/6191830_DSC_4504.jpg\" title=\"wwwwwwwwwwww\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"2048\" height=\"1363\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/6191830_DSC_4504.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/6191830_DSC_4504.jpg 2048w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/6191830_DSC_4504-300x200.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/6191830_DSC_4504-1024x682.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/6191830_DSC_4504-768x511.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/6191830_DSC_4504-1536x1022.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>wwwwwwwwwwww<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/4ad383ad55d63a236eecc80cdd27e72a.jpg\" title=\"a\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"1500\" height=\"883\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/4ad383ad55d63a236eecc80cdd27e72a.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/4ad383ad55d63a236eecc80cdd27e72a.jpg 1500w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/4ad383ad55d63a236eecc80cdd27e72a-300x177.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/4ad383ad55d63a236eecc80cdd27e72a-1024x603.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/4ad383ad55d63a236eecc80cdd27e72a-768x452.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>a<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-mi-pham-spa-4.jpg\" title=\"zzzzzz\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"650\" height=\"433\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-mi-pham-spa-4.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-mi-pham-spa-4.jpg 650w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/trung-bay-mi-pham-spa-4-300x200.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>zzzzzz<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hoat-dong-tu-van-khach-hang-cua-doanh-nghiep-tai-techmart-hang-nam-1665568226.jpg\" title=\"yyyyyyyyyyyyy\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"1280\" height=\"849\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hoat-dong-tu-van-khach-hang-cua-doanh-nghiep-tai-techmart-hang-nam-1665568226.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hoat-dong-tu-van-khach-hang-cua-doanh-nghiep-tai-techmart-hang-nam-1665568226.jpg 1280w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hoat-dong-tu-van-khach-hang-cua-doanh-nghiep-tai-techmart-hang-nam-1665568226-300x199.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hoat-dong-tu-van-khach-hang-cua-doanh-nghiep-tai-techmart-hang-nam-1665568226-1024x679.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/hoat-dong-tu-van-khach-hang-cua-doanh-nghiep-tai-techmart-hang-nam-1665568226-768x509.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>yyyyyyyyyyyyy<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/sap-dien-ra-trien-lam-thuc-pham-va-do-uong-viet-nam-lan-thu-24.jpg\" title=\"ttttttttttttttt\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image box-shadow-2 box-shadow-4-hover image-cover\" style=\"padding-top:130px;\">\n                <img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/sap-dien-ra-trien-lam-thuc-pham-va-do-uong-viet-nam-lan-thu-24.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1025,1024,1023,1022,1021,1020,1019,1018\" style=\"normal\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"small\" columns__sm=\"2\" depth=\"2\" depth_hover=\"4\" image_height=\"130px\" image_size=\"original\" text_align=\"center\" visibility=\"hidden\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/sap-dien-ra-trien-lam-thuc-pham-va-do-uong-viet-nam-lan-thu-24.jpg 600w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/sap-dien-ra-trien-lam-thuc-pham-va-do-uong-viet-nam-lan-thu-24-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p>ttttttttttttttt<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div>\n         <\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_285468143 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section thuong-hieu-section\" id=\"section_1064620385\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1215977924\">\n\n\t<div id=\"col-861185686\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-316082336\">\n\n\t<div id=\"col-431185358\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 class=\"uppercase\"><span style=\"color: #3c3469; font-size: 150%;\">Organizer<\/span><\/h3>\n<p><img decoding=\"async\" class=\"wp-image-4519 alignleft\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-den.png\" alt=\"\" width=\"130\" height=\"95\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-den.png 315w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-den-300x219.png 300w\" sizes=\"(max-width: 130px) 100vw, 130px\" \/><\/p>\n\t<div id=\"gap-1302403819\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1302403819 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3796391365\" class=\"text hidden\">\n\t\t\n\n\t<div class=\"gs_logo_area gs_logo_area_51 slider1\" style=\"opacity: 0; visibility: hidden;\">\n\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":false,\"pauseOnHover\":true,\"ticker\":false,\"navs\":false,\"navs_pos\":\"left-right-out\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":2,\"tabletLogos\":2,\"mobileLogos\":1,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/atfaexpo.vn\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai-300x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"ATFA\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai-300x300.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai-150x150.png 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai-270x270.png 270w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai-192x192.png 192w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai-180x180.png 180w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai-32x32.png 32w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/07\/cropped-Logo-ATFA-ai.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-735064253\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 class=\"uppercase\"><span style=\"color: #3c3469; font-size: 150%;\">Patronages<\/span><\/h3>\n\t<div id=\"gap-1212351078\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1212351078 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"gs_logo_area gs_logo_area_53 slider1\" style=\"opacity: 0; visibility: hidden;\">\n\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":false,\"pauseOnHover\":true,\"ticker\":false,\"navs\":false,\"navs_pos\":\"left-right-out\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":2,\"tabletLogos\":2,\"mobileLogos\":1,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"269\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/VCCI-300x105-1-300x269.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"VCCI\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/VCCI-300x105-1-300x269.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/VCCI-300x105-1.png 321w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"283\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/Hiep-hoi-thuc-pham-chuc-nang-283x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"VAFF\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/Hiep-hoi-thuc-pham-chuc-nang-283x300.png 283w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/Hiep-hoi-thuc-pham-chuc-nang.png 633w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-861185686 > .col-inner {\n  margin: -50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1742453106\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1681509959\">\n\n\t<div id=\"col-816903774\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h3 class=\"uppercase\"><span style=\"color: #3c3469;\"><span style=\"font-size: 30.24px;\">CO-ORGANIZERS<\/span><\/span><\/h3>\n<p><img decoding=\"async\" class=\"size-medium wp-image-4539 alignleft\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-300x81.png\" alt=\"\" width=\"300\" height=\"81\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-300x81.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-350x96.png 350w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell.png 354w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><span style=\"font-size: 14.4px;\">\u00a0<\/span><\/p>\n\t<div id=\"text-3086921522\" class=\"text hidden\">\n\t\t\n\n\t<div class=\"gs_logo_area gs_logo_area_57 slider1\" style=\"opacity: 0; visibility: hidden;\">\n\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":false,\"pauseOnHover\":true,\"ticker\":false,\"navs\":false,\"navs_pos\":\"bottom\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":5,\"tabletLogos\":3,\"mobileLogos\":2,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"81\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-300x81.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Korea Wellness\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-300x81.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-350x96.png 350w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell.png 354w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<\/div>\n\t\n\t<div id=\"gap-423674051\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-423674051 {\n  padding-top: 69px;\n}\n@media (min-width:550px) {\n  #gap-423674051 {\n    padding-top: 140px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-1742453106 > .col-inner {\n  margin: -50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1783730952\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-896107209\">\n\n\t<div id=\"col-1910346044\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 class=\"uppercase\"><span style=\"color: #3c3469; font-size: 150%;\">Strategic Communication Partner<\/span><\/h3>\n\t<div id=\"gap-394088549\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-394088549 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"gs_logo_area gs_logo_area_55 slider1\" style=\"opacity: 0; visibility: hidden;\">\n\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":false,\"pauseOnHover\":true,\"ticker\":false,\"navs\":false,\"navs_pos\":\"left-right-out\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":2,\"tabletLogos\":2,\"mobileLogos\":1,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"211\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Logo-FM-co-vien@4x-1-300x211.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Gold Sun focus Media\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Logo-FM-co-vien@4x-1-300x211.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Logo-FM-co-vien@4x-1-1024x719.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Logo-FM-co-vien@4x-1-768x539.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Logo-FM-co-vien@4x-1-1536x1079.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Logo-FM-co-vien@4x-1-2048x1438.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-648704794\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 class=\"uppercase\"><span style=\"color: #3c3469; font-size: 150%;\">Media Sponsors<\/span><\/h3>\n\t<div id=\"gap-615585019\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-615585019 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"gs_logo_area gs_logo_area_56 slider1\" style=\"opacity: 0; visibility: hidden;\">\n\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":false,\"pauseOnHover\":true,\"ticker\":false,\"navs\":false,\"navs_pos\":\"left-right-out\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":2,\"tabletLogos\":2,\"mobileLogos\":1,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"66\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/SUCKHOELOGO-2022-NEW-01-300x66.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Tap chi Suc khoe +\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/SUCKHOELOGO-2022-NEW-01-300x66.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/SUCKHOELOGO-2022-NEW-01-1024x225.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/SUCKHOELOGO-2022-NEW-01-768x169.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/SUCKHOELOGO-2022-NEW-01-1536x338.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/SUCKHOELOGO-2022-NEW-01-2048x451.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"124\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/logo-kienthucdulich.com_.vn_-300x124.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Ki\u1ebfn th\u1ee9c Du l\u1ecbch\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/logo-kienthucdulich.com_.vn_-300x124.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/logo-kienthucdulich.com_.vn_.png 364w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"244\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/logo-THDN-300x244.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Th\u01b0\u01a1ng hi\u1ec7u doanh nghi\u1ec7p\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/logo-THDN-300x244.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/logo-THDN-768x624.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/logo-THDN.jpg 831w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"185\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/Logo_TGTD-300x185.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Th\u1ebf gi\u1edbi ti\u00eau d\u00f9ng\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/Logo_TGTD-300x185.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/08\/Logo_TGTD.png 572w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-83270417\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 class=\"uppercase\"><span style=\"color: #3c3469; font-size: 150%;\">Strategic Partners<\/span><\/h3>\n\t<div id=\"gap-485107864\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-485107864 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"gs_logo_area gs_logo_area_52 slider1\" style=\"opacity: 0; visibility: hidden;\">\n\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":false,\"pauseOnHover\":true,\"ticker\":false,\"navs\":false,\"navs_pos\":\"left-right-out\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":5,\"tabletLogos\":3,\"mobileLogos\":2,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"171\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DEOU-300x171.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"DEOU\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DEOU-300x171.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DEOU-1024x585.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DEOU-768x439.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DEOU-1536x878.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DEOU-2048x1170.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"128\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Viewest-300x128.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Viewest\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Viewest-300x128.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Viewest-1024x438.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Viewest-768x329.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Viewest-1536x657.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Viewest-2048x876.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"163\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Trum-Gom-300x163.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Tr\u00f9m G\u1ed1m\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Trum-Gom-300x163.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Trum-Gom-1024x557.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Trum-Gom-768x418.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Trum-Gom-1536x835.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Trum-Gom-2048x1113.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Soyna-300x201.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"SoyNa\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Soyna-300x201.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Soyna-1024x688.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Soyna-768x516.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Soyna-1536x1031.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Soyna.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"105\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Meta-300x105.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Meta\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Meta-300x105.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Meta-1024x358.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Meta-768x269.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Meta-1536x538.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Meta-2048x717.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"115\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Level-300x115.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Level\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Level-300x115.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Level-1024x392.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Level-768x294.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Level-1536x589.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Level-2048x785.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/LaPaw-300x160.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"LaPaw\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/LaPaw-300x160.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/LaPaw-1024x545.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/LaPaw-768x409.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/LaPaw-1536x818.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/LaPaw-2048x1090.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"144\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/JNA-300x144.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"JNA\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/JNA-300x144.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/JNA-1024x492.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/JNA-768x369.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/JNA-1536x738.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/JNA-2048x984.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"129\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Gosinga-300x129.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"GOSINGA\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Gosinga-300x129.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Gosinga-1024x441.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Gosinga-768x331.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Gosinga-1536x661.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Gosinga-2048x882.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"92\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Elite-300x92.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"ELITE\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Elite-300x92.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Elite-1024x313.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Elite-768x235.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Elite-1536x469.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/Elite-2048x626.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"191\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/bearbrick-300x191.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"BEAR-BRICK\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/bearbrick-300x191.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/bearbrick-1024x651.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/bearbrick-768x488.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/bearbrick-1536x977.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/10\/bearbrick-2048x1303.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2095694592\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 class=\"uppercase\"><span style=\"color: #3c3469; font-size: 150%;\">Typical exhibitors<\/span><\/h3>\n\t<div id=\"gap-1697734221\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1697734221 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"gs_logo_area gs_logo_area_54 slider1\" style=\"opacity: 0; visibility: hidden;\">\n\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":false,\"pauseOnHover\":true,\"ticker\":false,\"navs\":false,\"navs_pos\":\"left-right-out\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":5,\"tabletLogos\":3,\"mobileLogos\":2,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"81\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-300x81.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"KOREA WELLNESS INSDUSTRY ASSOCIATION\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-300x81.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell-350x96.png 350w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-Kwell.png 354w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"221\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4861804546037_6d576a354f009272245875054fa780a0-300x221.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"FASO VIETNAM\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4861804546037_6d576a354f009272245875054fa780a0-300x221.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4861804546037_6d576a354f009272245875054fa780a0-1024x755.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4861804546037_6d576a354f009272245875054fa780a0-768x566.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4861804546037_6d576a354f009272245875054fa780a0.jpg 1506w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Pharmicell-300x300.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"PHARMICELL\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Pharmicell-300x300.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Pharmicell-1024x1024.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Pharmicell-150x150.jpg 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Pharmicell-768x768.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Pharmicell-1536x1536.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Pharmicell.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"270\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Meditox-300x270.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"MEDYTOX\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Meditox-300x270.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-Meditox.jpg 567w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"154\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-vnl-2-300x154.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"VINALINK\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-vnl-2-300x154.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-vnl-2-1024x527.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-vnl-2-768x395.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-vnl-2.png 1151w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"188\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-VR-300x188.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"VietRap\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-VR-300x188.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-VR-768x482.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-VR.jpg 894w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-TOKUSHI-300x225.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"TOKUSHI\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-TOKUSHI-300x225.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-TOKUSHI-1024x768.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-TOKUSHI-768x576.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-TOKUSHI.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Nong-san-TN_LOGO-1-212x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"N\u00f4ng S\u1ea3n T\u00e2y Nguy\u00ean\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Nong-san-TN_LOGO-1-212x300.png 212w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Nong-san-TN_LOGO-1-724x1024.png 724w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Nong-san-TN_LOGO-1-768x1086.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Nong-san-TN_LOGO-1-1086x1536.png 1086w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Nong-san-TN_LOGO-1-1448x2048.png 1448w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"240\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-HP-300x240.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"HP Vi\u1ec7t Nam\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-HP-300x240.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-HP-1024x819.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-HP-768x614.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-HP.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"63\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-SAO-THAI-DUONG-300x63.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Sao Th\u00e1i D\u01b0\u01a1ng\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-SAO-THAI-DUONG-300x63.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-SAO-THAI-DUONG-1024x213.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-SAO-THAI-DUONG-768x160.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-SAO-THAI-DUONG-1536x320.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-SAO-THAI-DUONG.png 1962w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-2-300x300.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Ph\u1edf Nam Nh\u1ea5t\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-2-300x300.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-2-150x150.jpg 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-2.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"103\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ORIFLAME_LOGO_STD-1-300x103.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"ORIFLAME\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ORIFLAME_LOGO_STD-1-300x103.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ORIFLAME_LOGO_STD-1-768x264.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ORIFLAME_LOGO_STD-1.png 979w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"134\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-MD-Queens-moi-300x134.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"MD Queens\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-MD-Queens-moi-300x134.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-MD-Queens-moi-768x342.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Logo-MD-Queens-moi.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/labehe-Logo-_1_-300x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"LABEHE\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/labehe-Logo-_1_-300x300.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/labehe-Logo-_1_-1024x1024.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/labehe-Logo-_1_-150x150.png 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/labehe-Logo-_1_-768x768.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/labehe-Logo-_1_-1536x1536.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/labehe-Logo-_1_-2048x2048.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790730041976_d17a49d026024c75a9a66e6c8eaab448-300x300.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"INNO LIVING\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790730041976_d17a49d026024c75a9a66e6c8eaab448-300x300.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790730041976_d17a49d026024c75a9a66e6c8eaab448-1024x1024.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790730041976_d17a49d026024c75a9a66e6c8eaab448-150x150.jpg 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790730041976_d17a49d026024c75a9a66e6c8eaab448-768x768.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790730041976_d17a49d026024c75a9a66e6c8eaab448-1536x1536.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790730041976_d17a49d026024c75a9a66e6c8eaab448.jpg 1850w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813314904267_f31edc0a41826243506652df565e6096-300x94.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"HealthSK\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813314904267_f31edc0a41826243506652df565e6096-300x94.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813314904267_f31edc0a41826243506652df565e6096-768x242.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813314904267_f31edc0a41826243506652df565e6096.jpg 835w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"177\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO_FINAL_BT5.17-300x177.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"GB LIFE\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO_FINAL_BT5.17-300x177.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO_FINAL_BT5.17-1024x603.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO_FINAL_BT5.17-768x452.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO_FINAL_BT5.17.png 1224w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813047162694_1909de297c56b04842f40e61a468c985-300x135.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"FITNES Vi\u1ec7t Nam\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813047162694_1909de297c56b04842f40e61a468c985-300x135.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813047162694_1909de297c56b04842f40e61a468c985-1024x460.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813047162694_1909de297c56b04842f40e61a468c985-768x345.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813047162694_1909de297c56b04842f40e61a468c985-1536x691.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4813047162694_1909de297c56b04842f40e61a468c985-2048x921.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"282\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-ERMRI-300x282.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"ERMRI\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-ERMRI-300x282.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-ERMRI-1024x962.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-ERMRI-768x721.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-ERMRI-1536x1443.jpg 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-ERMRI.jpg 1977w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790500573627_e62e703965ea7b08c294e6b6c76f701e-300x180.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"C\u00f4ng ty Nh\u01b0 Ho\u00e0ng\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790500573627_e62e703965ea7b08c294e6b6c76f701e-300x180.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4790500573627_e62e703965ea7b08c294e6b6c76f701e.jpg 514w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"248\" height=\"203\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4787836501618_22aa93992de89b1807706fb87fac4a27.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"C\u00f4ng ty Ho\u00e0ng Ph\u00fa\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"252\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-com-pho-xua-1-300x252.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"C\u1ed1m Ph\u1ed1 X\u01b0a\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-com-pho-xua-1-300x252.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/logo-com-pho-xua-1.png 469w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"69\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-1-300x69.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"COWAY\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-1-300x69.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-1-1024x235.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-1-768x176.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-1-1536x352.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-1-2048x470.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-300x226.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Ch\u00e8 Th\u1ecbnh An\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-300x226.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-1024x771.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO-768x578.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/LOGO.jpg 1037w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"252\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4776367384957_a2e75f4159d1157825278f37e5bc1a47-300x252.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"C\u00e0 ph\u00ea Ho\u00e0ng Hi\u1ec7p\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4776367384957_a2e75f4159d1157825278f37e5bc1a47-300x252.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4776367384957_a2e75f4159d1157825278f37e5bc1a47-768x646.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/z4776367384957_a2e75f4159d1157825278f37e5bc1a47.jpg 850w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"145\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOMOM-300x145.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Wandomom Association Corporation\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOMOM-300x145.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOMOM-1024x495.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOMOM-768x372.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOMOM-1536x743.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOMOM-2048x991.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"120\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOBADA-300x120.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Wandobada Fishery Association Corp.\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOBADA-300x120.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOBADA-1024x410.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOBADA-768x307.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOBADA-1536x615.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/WANDOBADA-2048x820.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/SUCHANG-lnc-300x300.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"SUCHANG lnc\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/SUCHANG-lnc-300x300.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/SUCHANG-lnc-150x150.jpg 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/SUCHANG-lnc.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"177\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/STEP.V-300x177.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"STEP.V\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/STEP.V-300x177.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/STEP.V-768x452.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/STEP.V.jpg 1004w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"87\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ROCKCHEF-300x87.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"ROCKCHEF\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ROCKCHEF-300x87.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ROCKCHEF.png 383w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"155\" height=\"130\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/ONGGOJIB-AGRICULTURAL-ASSOCIATION-CORPORATION.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"ONGGOJIB AGRICULTURAL ASSOCIATION CORPORATION\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"243\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/NARICHAN1-min-300x243.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Narichan\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/NARICHAN1-min-300x243.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/NARICHAN1-min-1024x828.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/NARICHAN1-min-768x621.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/NARICHAN1-min-1536x1243.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/NARICHAN1-min-2048x1657.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOWALL-COOP-300x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Mowall Coop.\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOWALL-COOP-300x300.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOWALL-COOP-1024x1024.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOWALL-COOP-150x150.png 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOWALL-COOP-768x768.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOWALL-COOP-1536x1536.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOWALL-COOP-2048x2048.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"271\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOMYOUNG-BIO-271x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Mom&#038;Young Bio Agricultural Corporation\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOMYOUNG-BIO-271x300.png 271w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOMYOUNG-BIO-926x1024.png 926w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOMYOUNG-BIO-768x849.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOMYOUNG-BIO-1389x1536.png 1389w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/MOMYOUNG-BIO-1852x2048.png 1852w\" sizes=\"(max-width: 271px) 100vw, 271px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"45\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/miceonf-300x45.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Miceonf\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/miceonf-300x45.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/miceonf.png 392w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"146\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KEUMSAN-GINSENG-300x146.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"KEUMSAN GINSENG MYUNGGA\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KEUMSAN-GINSENG-300x146.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KEUMSAN-GINSENG-1024x498.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KEUMSAN-GINSENG-768x374.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KEUMSAN-GINSENG-1536x747.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KEUMSAN-GINSENG-2048x996.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"79\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KDY-ALOE.-Co-Ltd-300x79.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"KDY ALOE., Co Ltd\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KDY-ALOE.-Co-Ltd-300x79.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/KDY-ALOE.-Co-Ltd.png 389w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"290\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JUSUNGFARM-290x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"JUSUNGFARM CO.,LTD.\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JUSUNGFARM-290x300.png 290w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JUSUNGFARM-990x1024.png 990w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JUSUNGFARM-768x794.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JUSUNGFARM-1485x1536.png 1485w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JUSUNGFARM-1980x2048.png 1980w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"159\" height=\"77\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JirisanCheoRum-Farming.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"JirisanCheoRum Farming\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"142\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JEJUBONCHO-300x142.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"JEJUBONCHO\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JEJUBONCHO-300x142.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JEJUBONCHO-1024x486.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JEJUBONCHO-768x364.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JEJUBONCHO.jpg 1054w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"105\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JECHEON-KOREAN-MEDICINE-300x105.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Jecheon Koreanmedicine Bio Foundation Corporation\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JECHEON-KOREAN-MEDICINE-300x105.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JECHEON-KOREAN-MEDICINE-1024x357.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JECHEON-KOREAN-MEDICINE-768x268.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JECHEON-KOREAN-MEDICINE-1536x536.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/JECHEON-KOREAN-MEDICINE-2048x715.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"275\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/IKSAN-JEWELRY-275x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Iksan Jewelry Chain Co., ltd.\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/IKSAN-JEWELRY-275x300.png 275w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/IKSAN-JEWELRY-939x1024.png 939w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/IKSAN-JEWELRY-768x838.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/IKSAN-JEWELRY.png 1392w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"131\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Hwangtae-Story-Farming-Association-Corporation-300x131.jpg\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Hwangtae Story Farming Association Corporation\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Hwangtae-Story-Farming-Association-Corporation-300x131.jpg 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Hwangtae-Story-Farming-Association-Corporation-1024x448.jpg 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Hwangtae-Story-Farming-Association-Corporation-768x336.jpg 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Hwangtae-Story-Farming-Association-Corporation.jpg 1510w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"101\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/HANYEOUL-BIO-300x101.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Hanyeoul Bio Valley Co,.LTD\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/HANYEOUL-BIO-300x101.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/HANYEOUL-BIO-1024x344.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/HANYEOUL-BIO-768x258.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/HANYEOUL-BIO-1536x515.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/HANYEOUL-BIO-2048x687.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"231\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Gimpo-Agri-food-Co.Ltd_-300x231.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Gimpo Agri-food Co.Ltd\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Gimpo-Agri-food-Co.Ltd_-300x231.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Gimpo-Agri-food-Co.Ltd_-768x591.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Gimpo-Agri-food-Co.Ltd_.png 796w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GW-CORP-300x300.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"GW Corporation\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GW-CORP-300x300.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GW-CORP-150x150.png 150w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GW-CORP-768x768.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GW-CORP.png 924w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREENBEES-1-300x117.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"GREENBEES\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREENBEES-1-300x117.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREENBEES-1.png 407w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"148\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREEN-FB-300x148.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Green F&#038;B\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREEN-FB-300x148.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREEN-FB-1024x504.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREEN-FB-768x378.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREEN-FB-1536x757.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GREEN-FB-2048x1009.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GAVO-FARM-300x75.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"GAVOFARMS CO.,LTD\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GAVO-FARM-300x75.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GAVO-FARM-1024x258.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GAVO-FARM-768x193.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GAVO-FARM-1536x386.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/GAVO-FARM-2048x515.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"230\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEPUNGNYEON-300x230.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Daepungnyeon\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEPUNGNYEON-300x230.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEPUNGNYEON-1024x784.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEPUNGNYEON-768x588.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEPUNGNYEON.png 1082w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEHANJUJO-CO.-LTD-1.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"DAEHANJUJO CO., LTD.\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEHANJUJO-CO.-LTD-1.png 160w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/DAEHANJUJO-CO.-LTD-1-150x150.png 150w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"264\" height=\"55\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/Chamotdeul.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"Chamotdeul Co., Ltd\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"172\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/CONF-LLC-300x172.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"CONF LLC\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/CONF-LLC-300x172.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/CONF-LLC-1024x586.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/CONF-LLC-768x439.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/CONF-LLC-1536x878.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/CONF-LLC.png 1943w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/239BIO-Inc-300x158.png\" class=\"gs-logo--img wp-post-image\" alt=\"\" title=\"239BIO Inc.\" srcset=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/239BIO-Inc-300x158.png 300w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/239BIO-Inc-1024x538.png 1024w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/239BIO-Inc-768x403.png 768w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/239BIO-Inc-1536x807.png 1536w, https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2023\/11\/239BIO-Inc-2048x1075.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1064620385 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"page-single-page-nav-transparent-light.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1353","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - wellnessexpo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wellnessexpo.com.vn\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - wellnessexpo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wellnessexpo.com.vn\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"wellnessexpo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T02:56:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-den.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"6 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wellnessexpo.com.vn\/#website\",\"url\":\"https:\/\/wellnessexpo.com.vn\/\",\"name\":\"wellnessexpo\",\"description\":\"D\\u1ecbch v\\u1ee5 thi\\u1ebft k\\u1ebf website chuy\\u00ean nghi\\u1ec7p - uy t\\u00edn\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/wellnessexpo.com.vn\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wellnessexpo.com.vn\/en\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/wellnessexpo.com.vn\/wp-content\/uploads\/2024\/11\/Logo-den.png\",\"width\":315,\"height\":230},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wellnessexpo.com.vn\/en\/#webpage\",\"url\":\"https:\/\/wellnessexpo.com.vn\/en\/\",\"name\":\"Home - wellnessexpo\",\"isPartOf\":{\"@id\":\"https:\/\/wellnessexpo.com.vn\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wellnessexpo.com.vn\/en\/#primaryimage\"},\"datePublished\":\"2021-05-04T01:23:40+00:00\",\"dateModified\":\"2025-07-11T02:56:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wellnessexpo.com.vn\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wellnessexpo.com.vn\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wellnessexpo.com.vn\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wellnessexpo.com.vn\/en\/\",\"url\":\"https:\/\/wellnessexpo.com.vn\/en\/\",\"name\":\"Trang ch\\u1ee7\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wellnessexpo.com.vn\/en\/\",\"url\":\"https:\/\/wellnessexpo.com.vn\/en\/\",\"name\":\"Home\"}}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/pages\/1353"}],"collection":[{"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/comments?post=1353"}],"version-history":[{"count":60,"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/pages\/1353\/revisions"}],"predecessor-version":[{"id":4846,"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/pages\/1353\/revisions\/4846"}],"wp:attachment":[{"href":"https:\/\/wellnessexpo.com.vn\/en\/wp-json\/wp\/v2\/media?parent=1353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}